{"id":10241,"date":"2026-03-18T13:52:47","date_gmt":"2026-03-18T12:52:47","guid":{"rendered":"https:\/\/medeora.de\/?p=10241"},"modified":"2026-03-18T13:52:47","modified_gmt":"2026-03-18T12:52:47","slug":"access-control-post-4-4-access-control-is-responsibility","status":"publish","type":"post","link":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/","title":{"rendered":"Access control Post 4\/4 &#8211; Access control is responsibility"},"content":{"rendered":"<p>Conclusion of our topic block on the new roles &amp; rights concept.<\/p>\n<p>Access control is not just an IT issue. It is a question of responsibility.<br \/>\nAnyone responsible for research bears responsibility for:<br \/>\n&#8211; sensitive study data<br \/>\n&#8211; biological samples<br \/>\n&#8211; traceability and data protection <\/p>\n<p>Precise access control ensures that:<br \/>\n&#8211; Responsibilities are clearly defined<br \/>\n&#8211; Access remains traceable at all times<br \/>\n&#8211; Compliance is achieved without additional effort<\/p>\n<p>The new roles &amp; rights concept in BioARCHIVE was developed precisely for this purpose:<br \/>\n\ud83d\udc49 Control down to field level<br \/>\n\ud83d\udc49 Individual roles per user<br \/>\n\ud83d\udc49 Easily configurable, customizable at any time<\/p>\n<p>We have provided an overview in the introductory post.<br \/>\nYou can find more information on our website.<\/p>\n<p>\u27a1\ufe0f BioARCHIVE from MEDEORA &#8211; Your Partner for Digital Labs and Connected Research<br \/>\n\ud83d\uddd3\ufe0f Update available from May 2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conclusion of our topic block on the new roles &amp; rights concept. Access control is not just an IT issue. It is a question of responsibility. Anyone responsible for research bears responsibility for: &#8211; sensitive study data &#8211; biological samples &#8211; traceability and data protection Precise access control ensures that: &#8211; Responsibilities are clearly defined [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[44],"tags":[],"class_list":["post-10241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Access control Post 4\/4 - Access control is responsibility - medeora.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Access control Post 4\/4 - Access control is responsibility - medeora.de\" \/>\n<meta property=\"og:description\" content=\"Conclusion of our topic block on the new roles &amp; rights concept. Access control is not just an IT issue. It is a question of responsibility. Anyone responsible for research bears responsibility for: &#8211; sensitive study data &#8211; biological samples &#8211; traceability and data protection Precise access control ensures that: &#8211; Responsibilities are clearly defined [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/\" \/>\n<meta property=\"og:site_name\" content=\"medeora.de\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-18T12:52:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medeora.de\/wp-content\/uploads\/2026\/03\/Post-4-\u2013-Responsibility.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"sysadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sysadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/2026\\\/03\\\/18\\\/access-control-post-4-4-access-control-is-responsibility\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/2026\\\/03\\\/18\\\/access-control-post-4-4-access-control-is-responsibility\\\/\"},\"author\":{\"name\":\"sysadmin\",\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/#\\\/schema\\\/person\\\/4762f7ba612a86644d969e4e8626e3ca\"},\"headline\":\"Access control Post 4\\\/4 &#8211; Access control is responsibility\",\"datePublished\":\"2026-03-18T12:52:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/2026\\\/03\\\/18\\\/access-control-post-4-4-access-control-is-responsibility\\\/\"},\"wordCount\":139,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/2026\\\/03\\\/18\\\/access-control-post-4-4-access-control-is-responsibility\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medeora.de\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Post-4-\u2013-Responsibility.png\",\"articleSection\":[\"Software\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/medeora.de\\\/en\\\/2026\\\/03\\\/18\\\/access-control-post-4-4-access-control-is-responsibility\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/2026\\\/03\\\/18\\\/access-control-post-4-4-access-control-is-responsibility\\\/\",\"url\":\"https:\\\/\\\/medeora.de\\\/en\\\/2026\\\/03\\\/18\\\/access-control-post-4-4-access-control-is-responsibility\\\/\",\"name\":\"Access control Post 4\\\/4 - Access control is responsibility - medeora.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/2026\\\/03\\\/18\\\/access-control-post-4-4-access-control-is-responsibility\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/2026\\\/03\\\/18\\\/access-control-post-4-4-access-control-is-responsibility\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medeora.de\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Post-4-\u2013-Responsibility.png\",\"datePublished\":\"2026-03-18T12:52:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/#\\\/schema\\\/person\\\/4762f7ba612a86644d969e4e8626e3ca\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/2026\\\/03\\\/18\\\/access-control-post-4-4-access-control-is-responsibility\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medeora.de\\\/en\\\/2026\\\/03\\\/18\\\/access-control-post-4-4-access-control-is-responsibility\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/2026\\\/03\\\/18\\\/access-control-post-4-4-access-control-is-responsibility\\\/#primaryimage\",\"url\":\"https:\\\/\\\/medeora.de\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Post-4-\u2013-Responsibility.png\",\"contentUrl\":\"https:\\\/\\\/medeora.de\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Post-4-\u2013-Responsibility.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/2026\\\/03\\\/18\\\/access-control-post-4-4-access-control-is-responsibility\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/medeora.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Access control Post 4\\\/4 &#8211; Access control is responsibility\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/medeora.de\\\/en\\\/\",\"name\":\"medeora.de\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medeora.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medeora.de\\\/en\\\/#\\\/schema\\\/person\\\/4762f7ba612a86644d969e4e8626e3ca\",\"name\":\"sysadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/445b8a7b143af21a66ebe66a6d9a090382d57781f3f1f729cea94597c1fea314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/445b8a7b143af21a66ebe66a6d9a090382d57781f3f1f729cea94597c1fea314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/445b8a7b143af21a66ebe66a6d9a090382d57781f3f1f729cea94597c1fea314?s=96&d=mm&r=g\",\"caption\":\"sysadmin\"},\"sameAs\":[\"https:\\\/\\\/medeora.de\"],\"url\":\"https:\\\/\\\/medeora.de\\\/en\\\/author\\\/sysadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Access control Post 4\/4 - Access control is responsibility - medeora.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/","og_locale":"en_US","og_type":"article","og_title":"Access control Post 4\/4 - Access control is responsibility - medeora.de","og_description":"Conclusion of our topic block on the new roles &amp; rights concept. Access control is not just an IT issue. It is a question of responsibility. Anyone responsible for research bears responsibility for: &#8211; sensitive study data &#8211; biological samples &#8211; traceability and data protection Precise access control ensures that: &#8211; Responsibilities are clearly defined [&hellip;]","og_url":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/","og_site_name":"medeora.de","article_published_time":"2026-03-18T12:52:47+00:00","og_image":[{"url":"https:\/\/medeora.de\/wp-content\/uploads\/2026\/03\/Post-4-\u2013-Responsibility.png","width":1,"height":1,"type":"image\/png"}],"author":"sysadmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"sysadmin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/#article","isPartOf":{"@id":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/"},"author":{"name":"sysadmin","@id":"https:\/\/medeora.de\/en\/#\/schema\/person\/4762f7ba612a86644d969e4e8626e3ca"},"headline":"Access control Post 4\/4 &#8211; Access control is responsibility","datePublished":"2026-03-18T12:52:47+00:00","mainEntityOfPage":{"@id":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/"},"wordCount":139,"commentCount":0,"image":{"@id":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/#primaryimage"},"thumbnailUrl":"https:\/\/medeora.de\/wp-content\/uploads\/2026\/03\/Post-4-\u2013-Responsibility.png","articleSection":["Software"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/","url":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/","name":"Access control Post 4\/4 - Access control is responsibility - medeora.de","isPartOf":{"@id":"https:\/\/medeora.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/#primaryimage"},"image":{"@id":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/#primaryimage"},"thumbnailUrl":"https:\/\/medeora.de\/wp-content\/uploads\/2026\/03\/Post-4-\u2013-Responsibility.png","datePublished":"2026-03-18T12:52:47+00:00","author":{"@id":"https:\/\/medeora.de\/en\/#\/schema\/person\/4762f7ba612a86644d969e4e8626e3ca"},"breadcrumb":{"@id":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/#primaryimage","url":"https:\/\/medeora.de\/wp-content\/uploads\/2026\/03\/Post-4-\u2013-Responsibility.png","contentUrl":"https:\/\/medeora.de\/wp-content\/uploads\/2026\/03\/Post-4-\u2013-Responsibility.png"},{"@type":"BreadcrumbList","@id":"https:\/\/medeora.de\/en\/2026\/03\/18\/access-control-post-4-4-access-control-is-responsibility\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/medeora.de\/en\/"},{"@type":"ListItem","position":2,"name":"Access control Post 4\/4 &#8211; Access control is responsibility"}]},{"@type":"WebSite","@id":"https:\/\/medeora.de\/en\/#website","url":"https:\/\/medeora.de\/en\/","name":"medeora.de","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medeora.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/medeora.de\/en\/#\/schema\/person\/4762f7ba612a86644d969e4e8626e3ca","name":"sysadmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/445b8a7b143af21a66ebe66a6d9a090382d57781f3f1f729cea94597c1fea314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/445b8a7b143af21a66ebe66a6d9a090382d57781f3f1f729cea94597c1fea314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/445b8a7b143af21a66ebe66a6d9a090382d57781f3f1f729cea94597c1fea314?s=96&d=mm&r=g","caption":"sysadmin"},"sameAs":["https:\/\/medeora.de"],"url":"https:\/\/medeora.de\/en\/author\/sysadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/medeora.de\/en\/wp-json\/wp\/v2\/posts\/10241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medeora.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medeora.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medeora.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/medeora.de\/en\/wp-json\/wp\/v2\/comments?post=10241"}],"version-history":[{"count":1,"href":"https:\/\/medeora.de\/en\/wp-json\/wp\/v2\/posts\/10241\/revisions"}],"predecessor-version":[{"id":10389,"href":"https:\/\/medeora.de\/en\/wp-json\/wp\/v2\/posts\/10241\/revisions\/10389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medeora.de\/en\/wp-json\/wp\/v2\/media\/10254"}],"wp:attachment":[{"href":"https:\/\/medeora.de\/en\/wp-json\/wp\/v2\/media?parent=10241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medeora.de\/en\/wp-json\/wp\/v2\/categories?post=10241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medeora.de\/en\/wp-json\/wp\/v2\/tags?post=10241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}